{"id":4,"name":"Linda","url":"","description":"","link":"https:\/\/megamillionsonline.de\/mk\/author\/linda\/","slug":"linda","avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/6edb9cab7e0f18bf686cdb84f48d853cdd6e873f2e0112f1db4ee1e1262f5a70?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/6edb9cab7e0f18bf686cdb84f48d853cdd6e873f2e0112f1db4ee1e1262f5a70?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/6edb9cab7e0f18bf686cdb84f48d853cdd6e873f2e0112f1db4ee1e1262f5a70?s=96&d=mm&r=g"},"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Linda, Author at<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/megamillionsonline.de\/mk\/author\/linda\/\" \/>\n<meta property=\"og:locale\" content=\"mk_MK\" \/>\n<meta property=\"og:type\" content=\"profile\" \/>\n<meta property=\"og:title\" content=\"Linda, Author at\" \/>\n<meta property=\"og:url\" content=\"https:\/\/megamillionsonline.de\/author\/linda\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/secure.gravatar.com\/avatar\/6edb9cab7e0f18bf686cdb84f48d853cdd6e873f2e0112f1db4ee1e1262f5a70?s=500&d=mm&r=g\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"ProfilePage\",\"@id\":\"https:\\\/\\\/megamillionsonline.de\\\/author\\\/linda\\\/\",\"url\":\"https:\\\/\\\/megamillionsonline.de\\\/author\\\/linda\\\/\",\"name\":\"Linda, Author at\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/megamillionsonline.de\\\/mk\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/megamillionsonline.de\\\/author\\\/linda\\\/#breadcrumb\"},\"inLanguage\":\"mk-MK\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/megamillionsonline.de\\\/author\\\/linda\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/megamillionsonline.de\\\/author\\\/linda\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/megamillionsonline.de\\\/mk\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Archives for Linda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/megamillionsonline.de\\\/mk\\\/#website\",\"url\":\"https:\\\/\\\/megamillionsonline.de\\\/mk\\\/\",\"name\":\"\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/megamillionsonline.de\\\/mk\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"mk-MK\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/megamillionsonline.de\\\/mk\\\/#\\\/schema\\\/person\\\/63d37547a4f8d52e7bd88ed6e0e4e8b8\",\"name\":\"Linda\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"mk-MK\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6edb9cab7e0f18bf686cdb84f48d853cdd6e873f2e0112f1db4ee1e1262f5a70?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6edb9cab7e0f18bf686cdb84f48d853cdd6e873f2e0112f1db4ee1e1262f5a70?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6edb9cab7e0f18bf686cdb84f48d853cdd6e873f2e0112f1db4ee1e1262f5a70?s=96&d=mm&r=g\",\"caption\":\"Linda\"},\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/megamillionsonline.de\\\/author\\\/linda\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Linda, Author at","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/megamillionsonline.de\/mk\/author\/linda\/","og_locale":"mk_MK","og_type":"profile","og_title":"Linda, Author at","og_url":"https:\/\/megamillionsonline.de\/author\/linda\/","og_image":[{"url":"https:\/\/secure.gravatar.com\/avatar\/6edb9cab7e0f18bf686cdb84f48d853cdd6e873f2e0112f1db4ee1e1262f5a70?s=500&d=mm&r=g","type":"","width":"","height":""}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"ProfilePage","@id":"https:\/\/megamillionsonline.de\/author\/linda\/","url":"https:\/\/megamillionsonline.de\/author\/linda\/","name":"Linda, Author at","isPartOf":{"@id":"https:\/\/megamillionsonline.de\/mk\/#website"},"breadcrumb":{"@id":"https:\/\/megamillionsonline.de\/author\/linda\/#breadcrumb"},"inLanguage":"mk-MK","potentialAction":[{"@type":"ReadAction","target":["https:\/\/megamillionsonline.de\/author\/linda\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/megamillionsonline.de\/author\/linda\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/megamillionsonline.de\/mk\/"},{"@type":"ListItem","position":2,"name":"Archives for Linda"}]},{"@type":"WebSite","@id":"https:\/\/megamillionsonline.de\/mk\/#website","url":"https:\/\/megamillionsonline.de\/mk\/","name":"","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/megamillionsonline.de\/mk\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"mk-MK"},{"@type":"Person","@id":"https:\/\/megamillionsonline.de\/mk\/#\/schema\/person\/63d37547a4f8d52e7bd88ed6e0e4e8b8","name":"Linda","image":{"@type":"ImageObject","inLanguage":"mk-MK","@id":"https:\/\/secure.gravatar.com\/avatar\/6edb9cab7e0f18bf686cdb84f48d853cdd6e873f2e0112f1db4ee1e1262f5a70?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6edb9cab7e0f18bf686cdb84f48d853cdd6e873f2e0112f1db4ee1e1262f5a70?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6edb9cab7e0f18bf686cdb84f48d853cdd6e873f2e0112f1db4ee1e1262f5a70?s=96&d=mm&r=g","caption":"Linda"},"mainEntityOfPage":{"@id":"https:\/\/megamillionsonline.de\/author\/linda\/"}}]}},"_links":{"self":[{"href":"https:\/\/megamillionsonline.de\/mk\/wp-json\/wp\/v2\/users\/4","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/megamillionsonline.de\/mk\/wp-json\/wp\/v2\/users"}]}}